{"id":519,"date":"2020-10-07T09:06:28","date_gmt":"2020-10-07T09:06:28","guid":{"rendered":"https:\/\/lapoulebeninoise.com\/?page_id=519"},"modified":"2020-10-07T09:06:28","modified_gmt":"2020-10-07T09:06:28","slug":"condition-general-dutilisation","status":"publish","type":"page","link":"https:\/\/lapoulebeninoise.com\/index.php\/condition-general-dutilisation\/","title":{"rendered":"CONDITION GENERAL D&rsquo;UTILISATION"},"content":{"rendered":"\n<p>VUE D\u2019ENSEMBLE<\/p>\n\n\n\n<p>Ce site web est exploit\u00e9 par La poule b\u00e9ninoise. Sur ce site, les termes \u00ab\u00a0nous\u00a0\u00bb, \u00ab\u00a0notre\u00a0\u00bb et \u00ab\u00a0nos\u00a0\u00bb font r\u00e9f\u00e9rence \u00e0 La poule b\u00e9ninoise &nbsp;.La poule &nbsp;B\u00e9ninoise propose ce site web, y compris toutes les informations, tous les outils et tous les services qui y sont disponibles pour vous, l\u2019utilisateur, sous r\u00e9serve de votre acceptation de l\u2019ensemble des modalit\u00e9s, conditions, politiques et avis \u00e9nonc\u00e9s ici.<\/p>\n\n\n\n<p>En visitant ce site et\/ou en achetant un de nos produits, vous vous engagez dans notre \u00ab\u00a0Service\u00a0\u00bb et acceptez d\u2019\u00eatre li\u00e9 par les modalit\u00e9s suivantes (\u00ab\u00a0Conditions G\u00e9n\u00e9rales de Vente\u00a0\u00bb, \u00ab\u00a0Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation\u00a0\u00bb, \u00ab\u00a0Conditions\u00a0\u00bb), y compris les modalit\u00e9s, conditions et politiques additionnelles auxquelles il est fait r\u00e9f\u00e9rence ici et\/ou accessibles par hyperlien. Ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation s\u2019appliquent \u00e0 tous les utilisateurs de ce site, incluant mais ne se limitant pas, aux utilisateurs qui naviguent sur le site, qui sont des vendeurs, des clients, des marchands, et\/ou des contributeurs de contenu.<\/p>\n\n\n\n<p>Veuillez lire attentivement ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation avant d\u2019acc\u00e9der \u00e0 ou d\u2019utiliser notre site web. En acc\u00e9dant \u00e0 ou en utilisant une quelconque partie de ce site, vous acceptez d\u2019\u00eatre li\u00e9 par ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation. Si vous n\u2019acceptez pas toutes les modalit\u00e9s et toutes les Conditions de cet accord, alors vous ne devez pas acc\u00e9der au site web ni utiliser les services qui y sont propos\u00e9s. Si ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation sont consid\u00e9r\u00e9es comme une offre, l\u2019acceptation se limite express\u00e9ment \u00e0 ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation.<\/p>\n\n\n\n<p>Toutes les nouvelles fonctionnalit\u00e9s et tous les nouveaux outils qui seront ajout\u00e9s ult\u00e9rieurement \u00e0 cette boutique seront \u00e9galement assujettis \u00e0 ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation. Vous pouvez consulter la version la plus r\u00e9cente des Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation \u00e0 tout moment sur cette page. Nous nous r\u00e9servons le droit de mettre \u00e0 jour, de changer ou de remplacer toute partie de ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation en publiant les mises \u00e0 jour et\/ou les modifications sur notre site web. Il vous incombe de consulter cette page r\u00e9guli\u00e8rement pour v\u00e9rifier si des modifications ont \u00e9t\u00e9 apport\u00e9es. Votre utilisation continue du site web ou votre acc\u00e8s \u00e0 celui-ci apr\u00e8s la publication de toute modification constitue une acception de votre part de ces modifications.<\/p>\n\n\n\n<p>Notre boutique est h\u00e9berg\u00e9e sur wordpress Inc. Ils nous fournissent la plate-forme e-commerce qui nous permet de vous vendre nos produits et services.<\/p>\n\n\n\n<p>ARTICLE 1 \u2013 CONDITIONS D\u2019UTILISATION DE SITE WEB<\/p>\n\n\n\n<p>En acceptant ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation, vous d\u00e9clarez que vous avez atteint l\u2019\u00e2ge de la majorit\u00e9 dans votre pays, \u00c9tat ou province de r\u00e9sidence, et que vous nous avez donn\u00e9 votre consentement pour permettre \u00e0 toute personne d\u2019\u00e2ge mineur \u00e0 votre charge d\u2019utiliser ce site web.<\/p>\n\n\n\n<p>L\u2019utilisation de nos produits \u00e0 toute fin ill\u00e9gale ou non autoris\u00e9e est interdite, et vous ne devez pas non plus, dans le cadre de l\u2019utilisation du Service, violer les lois de votre juridiction (incluant mais ne se limitant pas aux lois relatives aux droits d\u2019auteur).<\/p>\n\n\n\n<p>Vous ne devez pas transmettre de vers, de virus ou tout autre code de nature destructive.<\/p>\n\n\n\n<p>Toute infraction ou violation des pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation entra\u00eenera la r\u00e9siliation imm\u00e9diate de vos Services.<\/p>\n\n\n\n<p>ARTICLE 2 \u2013 CONDITIONS G\u00c9N\u00c9RALES<\/p>\n\n\n\n<p>Nous nous r\u00e9servons le droit de refuser \u00e0 tout moment l\u2019acc\u00e8s aux services \u00e0 toute personne, et ce, pour quelque raison que ce soit.<\/p>\n\n\n\n<p>Vous comprenez que votre contenu (\u00e0 l\u2019exclusion de vos informations de carte de cr\u00e9dit) pourrait \u00eatre transf\u00e9r\u00e9 de mani\u00e8re non chiffr\u00e9e, et cela sous-entend (a) des transmissions sur divers r\u00e9seaux; et (b) des changements pour se conformer et s\u2019adapter aux exigences techniques pour la connexion des r\u00e9seaux ou appareils. Les informations de carte de cr\u00e9dit sont toujours chiffr\u00e9es pendant la transmission sur les r\u00e9seaux.<\/p>\n\n\n\n<p>Vous acceptez de ne pas reproduire, dupliquer, copier, vendre, revendre ou exploiter une quelconque partie du Service ou utilisation du Service, ou un quelconque acc\u00e8s au Service ou contact sur le site web, par le biais duquel le Service est fourni, sans autorisation \u00e9crite expresse pr\u00e9alable de notre part.<\/p>\n\n\n\n<p>Les titres utilis\u00e9s dans cet accord sont inclus pour votre commodit\u00e9, et ne vont ni limiter ni affecter ces Conditions.<\/p>\n\n\n\n<p>ARTICLE 3 \u2013 EXACTITUDE, EXHAUSTIVIT\u00c9 ET ACTUALIT\u00c9 DES INFORMATIONS<\/p>\n\n\n\n<p>Nous ne sommes pas responsables si les informations disponibles sur ce site ne sont pas exactes, compl\u00e8tes ou \u00e0 jour. Le contenu de ce site est fourni \u00e0 titre indicatif uniquement et ne devrait pas constituer votre seule source d\u2019information pour prendre des d\u00e9cisions, sans consulter au pr\u00e9alable des sources d\u2019information plus exactes, plus compl\u00e8tes et actualis\u00e9es. Si vous d\u00e9cidez de vous fier au contenu pr\u00e9sent\u00e9 sur ce site, vous le faites \u00e0 votre propre risque.<\/p>\n\n\n\n<p>Ce site pourrait contenir certaines informations ant\u00e9rieures. Ces informations ant\u00e9rieures, par nature, ne sont pas \u00e0 jour et sont fournies \u00e0 titre indicatif seulement. Nous nous r\u00e9servons le droit de modifier le contenu de ce site \u00e0 tout moment, mais nous n\u2019avons aucune obligation de mettre \u00e0 jour les informations sur notre site. Vous acceptez qu\u2019il vous incombe de surveiller les modifications apport\u00e9es \u00e0 notre site.<\/p>\n\n\n\n<p>ARTICLE 4 \u2013 MODIFICATIONS APPORT\u00c9ES AU SERVICE ET AUX PRIX<\/p>\n\n\n\n<p>Les prix de nos produits peuvent \u00eatre modifi\u00e9s sans pr\u00e9avis.<\/p>\n\n\n\n<p>Nous nous r\u00e9servons le droit \u00e0 tout moment de modifier ou d\u2019interrompre le Service (ainsi que toute partie ou tout contenu du Service) sans pr\u00e9avis et en tout temps.<\/p>\n\n\n\n<p>Nous ne serons pas responsables envers vous ou toute autre tierce partie de toute modification de prix, suspension ou interruption du Service.<\/p>\n\n\n\n<p>ARTICLE 5 \u2013 PRODUITS OU SERVICES (le cas \u00e9ch\u00e9ant)<\/p>\n\n\n\n<p>Certains produits ou services peuvent \u00eatre exclusivement disponibles en ligne sur notre site web. Ces produits ou services peuvent \u00eatre disponibles en quantit\u00e9s limit\u00e9es et peuvent uniquement faire l\u2019objet de retours ou d\u2019\u00e9changes conform\u00e9ment \u00e0 notre Politique de Retour.<\/p>\n\n\n\n<p>Nous avons fait de notre mieux pour afficher aussi clairement que possible les couleurs et images de nos produits qui apparaissent sur notre boutique. Nous ne pouvons pas garantir que l\u2019affichage des couleurs par l\u2019\u00e9cran de votre ordinateur sera pr\u00e9cis.<\/p>\n\n\n\n<p>Nous nous r\u00e9servons le droit, sans toutefois \u00eatre oblig\u00e9s de le faire, de limiter les ventes de nos produits ou services \u00e0 toute personne, et dans toute r\u00e9gion g\u00e9ographique ou juridiction. Nous pourrions exercer ce droit au cas par cas. Nous nous r\u00e9servons le droit de limiter les quantit\u00e9s de tout produit ou service que nous offrons. Toutes les descriptions de produits et tous les prix des produits peuvent \u00eatre modifi\u00e9s en tout temps sans avis pr\u00e9alable, \u00e0 notre seule discr\u00e9tion. Nous nous r\u00e9servons le droit d\u2019arr\u00eater d\u2019offrir un produit \u00e0 tout moment. Toute offre de service ou de produit pr\u00e9sent\u00e9e sur ce site est nulle l\u00e0 o\u00f9 la loi l\u2019interdit.<\/p>\n\n\n\n<p>Nous ne garantissons pas que la qualit\u00e9 de tous les produits, services, informations, ou toute autre marchandise que vous avez obtenue ou achet\u00e9e r\u00e9pondra \u00e0 vos attentes, ni que toute erreur dans le Service sera corrig\u00e9e.<\/p>\n\n\n\n<p>ARTICLE 6 \u2013 EXACTITUDE DE LA FACTURATION ET DES INFORMATIONS DE COMPTE<\/p>\n\n\n\n<p>Nous nous r\u00e9servons le droit de refuser toute commande que vous passez aupr\u00e8s de nous. Nous pourrions, \u00e0 notre seule discr\u00e9tion, r\u00e9duire ou annuler les quantit\u00e9s achet\u00e9es par personne, par foyer ou par commande. Ces restrictions pourraient inclure des commandes pass\u00e9es par ou depuis le m\u00eame compte client, la m\u00eame carte de cr\u00e9dit, et\/ou des commandes qui utilisent la m\u00eame adresse de facturation et\/ou d\u2019exp\u00e9dition. Dans le cas o\u00f9 nous modifierions une commande ou si nous venions \u00e0 l\u2019annuler, nous pourrions tenter de vous avertir en vous contactant \u00e0 l\u2019e-mail et\/ou \u00e0 l\u2019adresse de facturation\/au num\u00e9ro de t\u00e9l\u00e9phone fourni au moment o\u00f9 la commande a \u00e9t\u00e9 pass\u00e9e. Nous nous r\u00e9servons le droit de limiter ou d\u2019interdire les commandes qui, \u00e0 notre seul jugement, pourraient sembler provenir de marchands, de revendeurs ou de distributeurs.<\/p>\n\n\n\n<p>Vous acceptez de fournir des informations de commande et de compte \u00e0 jour, compl\u00e8tes et exactes pour toutes les commandes pass\u00e9es sur notre boutique. Vous vous engagez \u00e0 mettre \u00e0 jour rapidement votre compte et vos autres informations, y compris votre adresse e-mail, vos num\u00e9ros de cartes de cr\u00e9dit et dates d\u2019expiration, pour que nous poussions compl\u00e9ter vos transactions et vous contacter si n\u00e9cessaire.<\/p>\n\n\n\n<p>Pour plus de d\u00e9tails, veuillez consulter notre Politique de Retour.<\/p>\n\n\n\n<p>ARTICLE 7 \u2013 OUTILS FACULTATIFS<\/p>\n\n\n\n<p>Nous pourrions vous fournir l\u2019acc\u00e8s \u00e0 des outils de tierces parties sur lesquels nous n\u2019exer\u00e7ons ni suivi, ni contr\u00f4le, ni influence.<\/p>\n\n\n\n<p>Vous reconnaissez et acceptez le fait que nous fournissons l\u2019acc\u00e8s \u00e0 de tels outils \u00ab\u00a0tels quels\u00a0\u00bb et \u00ab\u00a0selon la disponibilit\u00e9\u00a0\u00bb, sans aucune garantie, repr\u00e9sentation ou condition d\u2019aucune sorte et sans aucune approbation. Nous n\u2019aurons aucune responsabilit\u00e9 l\u00e9gale r\u00e9sultant de ou li\u00e9e \u00e0 l\u2019utilisation de ces outils facultatifs de tiers.<\/p>\n\n\n\n<p>Si vous utilisez les outils facultatifs offerts sur le site, vous le faites \u00e0 votre propre risque et \u00e0 votre propre discr\u00e9tion, et vous devriez consulter les conditions auxquelles ces outils sont offerts par le ou les fournisseurs tiers concern\u00e9s (s).<\/p>\n\n\n\n<p>Nous pourrions aussi, \u00e0 l\u2019avenir, offrir de nouveaux services et\/ou de nouvelles fonctionnalit\u00e9s sur notre site (incluant de nouveaux outils et de nouvelles ressources). Ces nouvelles fonctionnalit\u00e9s et ces nouveaux services seront \u00e9galement assujettis \u00e0 ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation.<\/p>\n\n\n\n<p>ARTICLE 8 \u2013 LIENS DE TIERS<\/p>\n\n\n\n<p>Certains contenus, produits et services disponibles par le biais de notre Service pourraient inclure des \u00e9l\u00e9ments provenant de tierces parties.<\/p>\n\n\n\n<p>Les liens provenant de tierces parties sur ce site pourraient vous rediriger vers des sites web de tiers qui ne sont pas affili\u00e9s \u00e0 nous. Nous ne sommes pas tenus d\u2019examiner ou d\u2019\u00e9valuer le contenu ou l\u2019exactitude de ces sites, et nous ne garantissons pas et n\u2019assumons aucune responsabilit\u00e9 quant \u00e0 tout contenu, site web, produit, service ou autre \u00e9l\u00e9ment accessible sur ou depuis ces sites tiers.<\/p>\n\n\n\n<p>Nous ne sommes pas responsables des pr\u00e9judices ou dommages li\u00e9s \u00e0 l\u2019achat ou \u00e0 l\u2019utilisation de biens, de services, de ressources, de contenu, ou de toute autre transaction effectu\u00e9e en rapport avec ces sites web de tiers. Veuillez lire attentivement les politiques et pratiques des tierces parties et assurez-vous de bien les comprendre avant de vous engager dans toute transaction. Les plaintes, r\u00e9clamations, pr\u00e9occupations, ou questions concernant les produits de ces tiers doivent \u00eatre soumises \u00e0 ces m\u00eames tiers.<\/p>\n\n\n\n<p>ARTICLE 9 \u2013 COMMENTAIRES, SUGGESTIONS ET AUTRES PROPOSITIONS D\u2019UTILISATEURS<\/p>\n\n\n\n<p>Si, \u00e0 notre demande, vous soumettez des contenus sp\u00e9cifiques (par exemple, pour participer \u00e0 des concours), ou si sans demande de notre part, vous envoyez des id\u00e9es cr\u00e9atives, des suggestions, des propositions, des plans ou d\u2019autres \u00e9l\u00e9ments, que ce soit en ligne, par e-mail, par courrier, ou autrement (collectivement, \u00ab\u00a0commentaires\u00a0\u00bb), vous nous accordez le droit, en tout temps, et sans restriction, d\u2019\u00e9diter, de copier, de publier, de distribuer, de traduire et d\u2019utiliser autrement et dans tout m\u00e9dia tout commentaire que vous nous envoyez. Nous ne sommes pas et ne devrons pas \u00eatre tenus (1) de maintenir la confidentialit\u00e9 des commentaires; (2) de payer une compensation \u00e0 quiconque pour tout commentaire fourni; (3) de r\u00e9pondre aux commentaires.<\/p>\n\n\n\n<p>Nous pourrions, mais n\u2019avons aucune obligation de le faire, surveiller, modifier ou supprimer le contenu que nous estimons, \u00e0 notre seule discr\u00e9tion, \u00eatre ill\u00e9gal, offensant, mena\u00e7ant, injurieux, diffamatoire, pornographique, obsc\u00e8ne ou autrement r\u00e9pr\u00e9hensible, ou qui enfreint toute propri\u00e9t\u00e9 intellectuelle ou ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation.<\/p>\n\n\n\n<p>Vous vous engagez \u00e0 \u00e9crire des commentaires qui ne violent pas les droits de tierces parties, y compris les droits d\u2019auteur, les marques d\u00e9pos\u00e9es, la confidentialit\u00e9, la personnalit\u00e9, ou d\u2019autres droits personnels ou de propri\u00e9t\u00e9. Vous convenez \u00e9galement que vos commentaires ne contiendront pas de contenu ill\u00e9gal, diffamatoire, offensif ou obsc\u00e8ne, et qu\u2019ils ne contiendront non plus pas de virus informatique ou d\u2019autres logiciels malveillants qui pourraient affecter de quelque mani\u00e8re que ce soit le fonctionnement du Service ou tout autre site web associ\u00e9. Vous ne pouvez pas utiliser de fausse adresse e-mail, pr\u00e9tendre \u00eatre quelqu\u2019un que vous n\u2019\u00eates pas, ou essayer de nous induire nous et\/ou les tierces parties en erreur quant \u00e0 l\u2019origine de vos commentaires. Vous \u00eates enti\u00e8rement responsable de tous les commentaires que vous publiez ainsi que de leur exactitude. Nous n\u2019assumons aucune responsabilit\u00e9 et d\u00e9clinons tout engagement quant \u00e0 tout commentaire que vous publiez ou que toute autre tierce partie publie.<\/p>\n\n\n\n<p>ARTICLE 10 \u2013 RENSEIGNEMENTS PERSONNELS<\/p>\n\n\n\n<p>La soumission de vos renseignements personnels sur notre boutique est r\u00e9gie par notre Politique de Confidentialit\u00e9. Cliquez ici pour consulter notre Politique de Confidentialit\u00e9.<\/p>\n\n\n\n<p>ARTICLE 11 \u2013 ERREURS, INEXACTITUDES ET OMISSIONS<\/p>\n\n\n\n<p>Il se pourrait qu\u2019il y ait parfois des informations sur notre site ou dans le Service qui pourraient contenir des erreurs typographiques, des inexactitudes ou des omissions qui pourraient \u00eatre relatives aux descriptions de produits, aux prix, aux promotions, aux offres, aux frais d\u2019exp\u00e9dition des produits, aux d\u00e9lais de livraison et \u00e0 la disponibilit\u00e9. Nous nous r\u00e9servons le droit de corriger toute erreur, inexactitude, omission, et de changer ou de mettre \u00e0 jour des informations ou d\u2019annuler des commandes, si une quelconque information dans le Service ou sur tout autre site web associ\u00e9 est inexacte, et ce, en tout temps et sans pr\u00e9avis (y compris apr\u00e8s que vous ayez pass\u00e9 votre commande).<\/p>\n\n\n\n<p>Nous ne sommes pas tenus de mettre \u00e0 jour, de modifier ou de clarifier les informations dans le Service ou sur tout autre site web associ\u00e9, incluant mais ne se limitant pas aux informations sur les prix, sauf si requis par la loi. Aucune date d\u00e9finie de mise \u00e0 jour ou d\u2019actualisation dans le Service ou sur tout autre site web associ\u00e9 ne devrait \u00eatre prise en compte pour conclure que les informations dans le Service ou sur tout autre site web associ\u00e9 ont \u00e9t\u00e9 modifi\u00e9es ou mises \u00e0 jour.<\/p>\n\n\n\n<p>ARTICLE 12 \u2013 UTILISATIONS INTERDITES<\/p>\n\n\n\n<p>En plus des interdictions \u00e9nonc\u00e9es dans les Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation, il vous est interdit d\u2019utiliser le site ou son contenu: (a) \u00e0 des fins ill\u00e9gales; (b) pour inciter des tiers \u00e0 r\u00e9aliser des actes ill\u00e9gaux ou \u00e0 y prendre part; (c) pour enfreindre toute ordonnance r\u00e9gionale ou toute loi, r\u00e8gle ou r\u00e9gulation internationale, f\u00e9d\u00e9rale, provinciale ou \u00e9tatique; (d) pour porter atteinte \u00e0 ou violer nos droits de propri\u00e9t\u00e9 intellectuelle ou ceux de tierces parties; (e) pour harceler, maltraiter, insulter, blesser, diffamer, calomnier, d\u00e9nigrer, intimider ou discriminer quiconque en fonction du sexe, de l\u2019orientation sexuelle, de la religion, de l\u2019origine ethnique, de la race, de l\u2019\u00e2ge, de l\u2019origine nationale, ou d\u2019un handicap; (f) pour soumettre des renseignements faux ou trompeurs; (g) pour t\u00e9l\u00e9verser ou transmettre des virus ou tout autre type de code malveillant qui sera ou pourrait \u00eatre utilis\u00e9 de mani\u00e8re \u00e0 compromettre la fonctionnalit\u00e9 ou le fonctionnement du Service ou de tout autre site web associ\u00e9, ind\u00e9pendant, ou d\u2019Internet; (h) pour recueillir ou suivre les renseignements personnels d\u2019autrui; (i) pour polluposter, hame\u00e7onner, d\u00e9tourner un domaine, extorquer des informations, parcourir, explorer ou balayer le web (ou toute autre ressource); (j) \u00e0 des fins obsc\u00e8nes ou immorales; ou (k) pour porter atteinte ou contourner les mesures de s\u00e9curit\u00e9 de notre Service, de tout autre site web, ou d\u2019Internet. Nous nous r\u00e9servons le droit de r\u00e9silier votre utilisation du Service ou de tout site web connexe pour avoir enfreint les utilisations interdites.<\/p>\n\n\n\n<p>ARTICLE 13 \u2013 EXCLUSION DE GARANTIES ET LIMITATION DE RESPONSABILIT\u00c9<\/p>\n\n\n\n<p>Nous ne garantissons ni ne pr\u00e9tendons en aucun cas que votre utilisation de notre Service sera ininterrompue, rapide, s\u00e9curis\u00e9e ou sans erreur.<\/p>\n\n\n\n<p>Nous ne garantissons pas que les r\u00e9sultats qui pourraient \u00eatre obtenus par le biais de l\u2019utilisation du Service seront exacts ou fiables.<\/p>\n\n\n\n<p>Vous acceptez que de temps \u00e0 autre, nous puissions supprimer le Service pour des p\u00e9riodes de temps ind\u00e9finies ou annuler le Service \u00e0 tout moment, sans vous avertir au pr\u00e9alable.<\/p>\n\n\n\n<p>Vous convenez express\u00e9ment que votre utilisation du Service, ou votre incapacit\u00e9 \u00e0 utiliser celui-ci, est \u00e0 votre seul risque. Le Service ainsi que tous les produits et services qui vous sont fournis par le biais du Service sont (sauf mention expresse du contraire de notre part) fournis \u00ab\u00a0tels quels\u00a0\u00bb et \u00ab\u00a0selon la disponibilit\u00e9\u00a0\u00bb pour votre utilisation, et ce sans repr\u00e9sentation, sans garanties et sans conditions d&rsquo;aucune sorte, expresses ou implicites, y compris toutes les garanties implicites de commercialisation ou de qualit\u00e9 marchande, d\u2019adaptation \u00e0 un usage particulier, de durabilit\u00e9, de titre et d\u2019absence de contrefa\u00e7on.<\/p>\n\n\n\n<p>La poule b\u00e9ninoise , nos directeurs, responsables, employ\u00e9s, soci\u00e9t\u00e9s affili\u00e9es, agents, contractants, stagiaires, fournisseurs, prestataires de services et conc\u00e9dants ne peuvent en aucun cas \u00eatre tenus responsables de toute blessure, perte, r\u00e9clamation, ou de dommages directs, indirects, accessoires, punitifs, sp\u00e9ciaux, ou dommages cons\u00e9cutifs de quelque nature qu\u2019ils soient, incluant mais ne se limitant pas \u00e0 la perte de profits, de revenus, d\u2019\u00e9conomies, de donn\u00e9es, aux co\u00fbts de remplacement ou tous dommages similaires, qu\u2019ils soient contractuels, d\u00e9lictuels (m\u00eame en cas de n\u00e9gligence), de responsabilit\u00e9 stricte ou autre, r\u00e9sultant de votre utilisation de tout service ou produit provenant de ce Service, ou quant \u00e0 toute autre r\u00e9clamation li\u00e9e de quelque mani\u00e8re que ce soit \u00e0 votre utilisation du Service ou de tout produit, incluant mais ne se limitant \u00e0 toute erreur ou omission dans tout contenu, ou \u00e0 toute perte ou tout dommage de toute sorte d\u00e9coulant de l\u2019utilisation du Service ou de tout contenu (ou produit) publi\u00e9, transmis, ou autrement rendu disponible par le biais du Service, m\u00eame si vous avez \u00e9t\u00e9 avertis de la possibilit\u00e9 qu\u2019ils surviennent. Parce que certains \u00c9tats ou certaines juridictions ne permettent pas d\u2019exclure ou de limiter la responsabilit\u00e9 quant aux dommages cons\u00e9cutifs ou accessoires, notre responsabilit\u00e9 sera limit\u00e9e dans la mesure maximale permise par la loi.<\/p>\n\n\n\n<p>ARTICLE 14 \u2013 INDEMNISATION<\/p>\n\n\n\n<p>Vous acceptez d\u2019indemniser, de d\u00e9fendre et de prot\u00e9ger la poule b\u00e9ninoise , notre soci\u00e9t\u00e9-m\u00e8re, nos filiales, soci\u00e9t\u00e9s affili\u00e9es, partenaires, responsables, directeurs, agents, contractants, conc\u00e9dants, prestataires de services, sous-traitants, fournisseurs, stagiaires et employ\u00e9s, quant \u00e0 toute r\u00e9clamation ou demande, incluant les honoraires raisonnables d\u2019avocat, faite par toute tierce partie \u00e0 cause de ou d\u00e9coulant de votre violation de ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation ou des documents auxquels ils font r\u00e9f\u00e9rence, ou de votre violation de toute loi ou des droits d\u2019un tiers.<\/p>\n\n\n\n<p>ARTICLE 15 \u2013 DISSOCIABILIT\u00c9<\/p>\n\n\n\n<p>Dans le cas o\u00f9 une disposition des pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation serait jug\u00e9e comme \u00e9tant ill\u00e9gale, nulle ou inapplicable, cette disposition pourra n\u00e9anmoins \u00eatre appliqu\u00e9e dans la pleine mesure permise par la loi, et la partie non applicable devra \u00eatre consid\u00e9r\u00e9e comme \u00e9tant dissoci\u00e9e de ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation, cette dissociation ne devra pas affecter la validit\u00e9 et l\u2019applicabilit\u00e9 de toutes les autres dispositions restantes.<\/p>\n\n\n\n<p>ARTICLE 16 \u2013 R\u00c9SILIATION<\/p>\n\n\n\n<p>Les obligations et responsabilit\u00e9s engag\u00e9es par les parties avant la date de r\u00e9siliation resteront en vigueur apr\u00e8s la r\u00e9siliation de cet accord et ce \u00e0 toutes les fins.<\/p>\n\n\n\n<p>Ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation sont effectives \u00e0 moins et jusqu\u2019\u00e0 ce qu\u2019elles soient r\u00e9sili\u00e9es par ou bien vous ou non. Vous pouvez r\u00e9silier ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation \u00e0 tout moment en nous avisant que vous ne souhaitez plus utiliser nos Services, ou lorsque vous cessez d\u2019utiliser notre site.<\/p>\n\n\n\n<p>Si nous jugeons, \u00e0 notre seule discr\u00e9tion, que vous \u00e9chouez, ou si nous soup\u00e7onnons que vous avez \u00e9t\u00e9 incapable de vous conformer aux modalit\u00e9s de ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation, nous pourrions aussi r\u00e9silier cet accord \u00e0 tout moment sans vous pr\u00e9venir \u00e0 l\u2019avance et vous resterez responsable de toutes les sommes redevables jusqu\u2019\u00e0 la date de r\u00e9siliation (celle-ci \u00e9tant incluse), et\/ou nous pourrions vous refuser l\u2019acc\u00e8s \u00e0 nos Services (ou \u00e0 toute partie de ceux-ci).<\/p>\n\n\n\n<p>ARTICLE 17 \u2013 INT\u00c9GRALIT\u00c9 DE L\u2019ACCORD<\/p>\n\n\n\n<p>Tout manquement de notre part \u00e0 l\u2019exercice ou \u00e0 l\u2019application de tout droit ou de toute disposition des pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation ne devrait pas constituer une renonciation \u00e0 ce droit ou \u00e0 cette disposition.<\/p>\n\n\n\n<p>Ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation ou toute autre politique ou r\u00e8gle d\u2019exploitation que nous publions sur ce site ou relativement au Service constituent l\u2019int\u00e9gralit\u00e9 de l\u2019entente et de l\u2019accord entre vous et nous et r\u00e9gissent votre utilisation du Service, et remplacent toutes les communications, propositions et tous les accords, ant\u00e9rieurs et contemporains, oraux ou \u00e9crits, entre vous et nous (incluant, mais ne se limitant pas \u00e0 toute version ant\u00e9rieure des Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation).<\/p>\n\n\n\n<p>Toute ambigu\u00eft\u00e9 quant \u00e0 l\u2019interpr\u00e9tation de ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation ne doit pas \u00eatre interpr\u00e9t\u00e9e en d\u00e9faveur de la partie r\u00e9dactrice.<\/p>\n\n\n\n<p>ARTICLE 18 \u2013 LOI APPLICABLE<\/p>\n\n\n\n<p>Ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation, ainsi que tout autre accord s\u00e9par\u00e9 par le biais duquel nous vous fournissons des Services seront r\u00e9gis et interpr\u00e9t\u00e9s en vertu des lois en vigueur \u00e0 la poule beninoise address.<\/p>\n\n\n\n<p>ARTICLE 19 \u2013 MODIFICATIONS APPORT\u00c9ES AUX CONDITIONS G\u00c9N\u00c9RALES DE VENTE ET D\u2019UTILISATION<\/p>\n\n\n\n<p>Vous pouvez consulter la version la plus r\u00e9cente des Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation \u00e0 tout moment sur cette page.<\/p>\n\n\n\n<p>Nous nous r\u00e9servons le droit, \u00e0 notre seule discr\u00e9tion, de mettre \u00e0 jour, de modifier ou de remplacer toute partie de ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation en publiant les mises \u00e0 jour et les changements sur notre site. Il vous incombe de visiter notre site r\u00e9guli\u00e8rement pour v\u00e9rifier si des changements ont \u00e9t\u00e9 apport\u00e9s. Votre utilisation continue de ou votre acc\u00e8s \u00e0 notre site apr\u00e8s la publication de toute modification apport\u00e9e \u00e0 ces Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation constitue une acceptation de ces modifications.<\/p>\n\n\n\n<p>ARTICLE 20 \u2013 COORDONN\u00c9ES<\/p>\n\n\n\n<p>Les questions concernant les Conditions G\u00e9n\u00e9rales de Vente et d\u2019Utilisation devraient nous \u00eatre envoy\u00e9es \u00e0 info@lapoulebeninoise.com.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VUE D\u2019ENSEMBLE Ce site web est exploit\u00e9 par La poule b\u00e9ninoise. Sur ce site, les termes \u00ab\u00a0nous\u00a0\u00bb, \u00ab\u00a0notre\u00a0\u00bb et \u00ab\u00a0nos\u00a0\u00bb font r\u00e9f\u00e9rence \u00e0 La poule b\u00e9ninoise &nbsp;.La poule &nbsp;B\u00e9ninoise propose ce site web, y compris toutes les informations, tous les outils et tous les services qui y sont disponibles pour vous, l\u2019utilisateur, sous r\u00e9serve de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/lapoulebeninoise.com\/index.php\/condition-general-dutilisation\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;CONDITION GENERAL D&rsquo;UTILISATION&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/lapoulebeninoise.com\/index.php\/wp-json\/wp\/v2\/pages\/519"}],"collection":[{"href":"https:\/\/lapoulebeninoise.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lapoulebeninoise.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lapoulebeninoise.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lapoulebeninoise.com\/index.php\/wp-json\/wp\/v2\/comments?post=519"}],"version-history":[{"count":1,"href":"https:\/\/lapoulebeninoise.com\/index.php\/wp-json\/wp\/v2\/pages\/519\/revisions"}],"predecessor-version":[{"id":520,"href":"https:\/\/lapoulebeninoise.com\/index.php\/wp-json\/wp\/v2\/pages\/519\/revisions\/520"}],"wp:attachment":[{"href":"https:\/\/lapoulebeninoise.com\/index.php\/wp-json\/wp\/v2\/media?parent=519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}